{"id":4730,"count":1,"description":"","link":"https:\/\/staytv.cr\/index.php\/tag\/municipalidad-de-santa-ana\/","name":"Municipalidad de Santa Ana","slug":"municipalidad-de-santa-ana","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.8.3.2 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/staytv.cr\/index.php\/tag\/municipalidad-de-santa-ana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.8.3.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Staytv - Medio de comunicaci\u00f3n digital de Costa Rica.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Municipalidad de Santa Ana - Staytv\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/staytv.cr\/index.php\/tag\/municipalidad-de-santa-ana\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/staytv.cr\/wp-content\/uploads\/portada.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/staytv.cr\/wp-content\/uploads\/portada.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t\t<meta property=\"og:image:height\" content=\"758\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/staytvcr\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Municipalidad de Santa Ana - Staytv\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/staytv.cr\/wp-content\/uploads\/portada.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staytv.cr\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4730\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staytv.cr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staytv.cr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staytv.cr\\\/index.php\\\/tag\\\/municipalidad-de-santa-ana\\\/#listItem\",\"name\":\"Municipalidad de Santa Ana\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staytv.cr\\\/index.php\\\/tag\\\/municipalidad-de-santa-ana\\\/#listItem\",\"position\":2,\"name\":\"Municipalidad de Santa Ana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staytv.cr#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/staytv.cr\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4730\\\/#collectionpage\",\"url\":\"https:\\\/\\\/staytv.cr\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4730\\\/\",\"name\":\"Municipalidad de Santa Ana - Staytv\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staytv.cr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staytv.cr\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4730\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staytv.cr\\\/#organization\",\"name\":\"Stay TV\",\"description\":\"Stay TV es un medio digital de noticias con base en Centroam\\u00e9rica, con cobertura local e internacional desde una mirada asi\\u00e1tica.\",\"url\":\"https:\\\/\\\/staytv.cr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/staytv.cr\\\/wp-content\\\/uploads\\\/cropped-StayTV_logo_oficial_simple.png\",\"@id\":\"https:\\\/\\\/staytv.cr\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4730\\\/#organizationLogo\",\"width\":2560,\"height\":769},\"image\":{\"@id\":\"https:\\\/\\\/staytv.cr\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/4730\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/staytvcr\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staytv.cr\\\/#website\",\"url\":\"https:\\\/\\\/staytv.cr\\\/\",\"name\":\"Staytv\",\"description\":\"Medio de comunicaci\\u00f3n digital de Costa Rica.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/staytv.cr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Municipalidad de Santa Ana - Staytv<\/title>\n\n","aioseo_head_json":{"title":"Municipalidad de Santa Ana - Staytv","description":"","canonical_url":"https:\/\/staytv.cr\/index.php\/tag\/municipalidad-de-santa-ana\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/staytv.cr\/wp-json\/wp\/v2\/tags\/4730\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/staytv.cr#listItem","position":1,"name":"Home","item":"https:\/\/staytv.cr","nextItem":{"@type":"ListItem","@id":"https:\/\/staytv.cr\/index.php\/tag\/municipalidad-de-santa-ana\/#listItem","name":"Municipalidad de Santa Ana"}},{"@type":"ListItem","@id":"https:\/\/staytv.cr\/index.php\/tag\/municipalidad-de-santa-ana\/#listItem","position":2,"name":"Municipalidad de Santa Ana","previousItem":{"@type":"ListItem","@id":"https:\/\/staytv.cr#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/staytv.cr\/wp-json\/wp\/v2\/tags\/4730\/#collectionpage","url":"https:\/\/staytv.cr\/wp-json\/wp\/v2\/tags\/4730\/","name":"Municipalidad de Santa Ana - Staytv","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/staytv.cr\/#website"},"breadcrumb":{"@id":"https:\/\/staytv.cr\/wp-json\/wp\/v2\/tags\/4730\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/staytv.cr\/#organization","name":"Stay TV","description":"Stay TV es un medio digital de noticias con base en Centroam\u00e9rica, con cobertura local e internacional desde una mirada asi\u00e1tica.","url":"https:\/\/staytv.cr\/","logo":{"@type":"ImageObject","url":"https:\/\/staytv.cr\/wp-content\/uploads\/cropped-StayTV_logo_oficial_simple.png","@id":"https:\/\/staytv.cr\/wp-json\/wp\/v2\/tags\/4730\/#organizationLogo","width":2560,"height":769},"image":{"@id":"https:\/\/staytv.cr\/wp-json\/wp\/v2\/tags\/4730\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/staytvcr\/"]},{"@type":"WebSite","@id":"https:\/\/staytv.cr\/#website","url":"https:\/\/staytv.cr\/","name":"Staytv","description":"Medio de comunicaci\u00f3n digital de Costa Rica.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/staytv.cr\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Staytv - Medio de comunicaci\u00f3n digital de Costa Rica.","og:type":"article","og:title":"Municipalidad de Santa Ana - Staytv","og:url":"https:\/\/staytv.cr\/index.php\/tag\/municipalidad-de-santa-ana\/","og:image":"https:\/\/staytv.cr\/wp-content\/uploads\/portada.jpg","og:image:secure_url":"https:\/\/staytv.cr\/wp-content\/uploads\/portada.jpg","og:image:width":2048,"og:image:height":758,"article:publisher":"https:\/\/www.facebook.com\/staytvcr","twitter:card":"summary_large_image","twitter:title":"Municipalidad de Santa Ana - Staytv","twitter:image":"https:\/\/staytv.cr\/wp-content\/uploads\/portada.jpg"},"aioseo_meta_data":{"term_id":"4730","title":null,"description":null,"keywords":null,"keyphrases":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"pillar_content":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"none","priority":null,"frequency":"default","tabs":null,"local_seo":null,"created":"2026-02-06 14:55:51","updated":"2026-02-06 14:55:51"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/staytv.cr\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tMunicipalidad de Santa Ana\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/staytv.cr"},{"label":"Municipalidad de Santa Ana","link":"https:\/\/staytv.cr\/index.php\/tag\/municipalidad-de-santa-ana\/"}],"_links":{"self":[{"href":"https:\/\/staytv.cr\/index.php\/wp-json\/wp\/v2\/tags\/4730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staytv.cr\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/staytv.cr\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/staytv.cr\/index.php\/wp-json\/wp\/v2\/posts?tags=4730"},{"href":"https:\/\/staytv.cr\/index.php\/wp-json\/wp\/v2\/podcast?tags=4730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}